{"id":39257,"date":"2026-05-15T12:03:20","date_gmt":"2026-05-15T12:03:20","guid":{"rendered":"https:\/\/joyasyasmin.com\/?post_type=product&#038;p=39257"},"modified":"2026-05-15T12:03:46","modified_gmt":"2026-05-15T12:03:46","slug":"pendiente-latido-de-luz","status":"publish","type":"product","link":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/","title":{"rendered":"Pendiente Latido de Luz"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Pendiente Latido de Luz de plata de ley 925 con cierre de tuerca a presi\u00f3n, dise\u00f1o delicado de doble coraz\u00f3n donde uno luce engastado con circonitas brillantes y el otro presenta un acabado en circon central. Una joya elegante y rom\u00e1ntica que simboliza uni\u00f3n, amor y luz, ideal para el d\u00eda a d\u00eda o para regalar.<\/p>\n","protected":false},"featured_media":39258,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"product_brand":[],"product_cat":[64],"product_tag":[],"class_list":["post-39257","product","type-product","status-publish","has-post-thumbnail","product_cat-aros-pendientes","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pendiente Latido de Luz - Yasmin<\/title>\n<meta name=\"description\" content=\"Pendiente Latido de Luz en forma de coraz\u00f3n en plata 925 con circonitas y circon central. Dise\u00f1o rom\u00e1ntico y brillante con cierre de tuerca a presi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:title\" content=\"Pendiente Latido de Luz - Yasmin\" \/>\n<meta property=\"og:description\" content=\"Pendiente Latido de Luz en forma de coraz\u00f3n en plata 925 con circonitas y circon central. Dise\u00f1o rom\u00e1ntico y brillante con cierre de tuerca a presi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/\" \/>\n<meta property=\"og:site_name\" content=\"Yasmin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Joyas-Yasmin-217664058934169\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-15T12:03:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/joyasyasmin.com\/wp-content\/uploads\/2026\/05\/pendiente-corazon-ilusion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/producto\\\/pendiente-latido-de-luz\\\/\",\"url\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/producto\\\/pendiente-latido-de-luz\\\/\",\"name\":\"Pendiente Latido de Luz - Yasmin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/producto\\\/pendiente-latido-de-luz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/producto\\\/pendiente-latido-de-luz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/joyasyasmin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/pendiente-corazon-ilusion.jpg\",\"datePublished\":\"2026-05-15T12:03:20+00:00\",\"dateModified\":\"2026-05-15T12:03:46+00:00\",\"description\":\"Pendiente Latido de Luz en forma de coraz\u00f3n en plata 925 con circonitas y circon central. Dise\u00f1o rom\u00e1ntico y brillante con cierre de tuerca a presi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/producto\\\/pendiente-latido-de-luz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/producto\\\/pendiente-latido-de-luz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/producto\\\/pendiente-latido-de-luz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/joyasyasmin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/pendiente-corazon-ilusion.jpg\",\"contentUrl\":\"https:\\\/\\\/joyasyasmin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/pendiente-corazon-ilusion.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"venta de pendiente ilus\u00f3n en forma de coraz\u00f3n de plata 925\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/producto\\\/pendiente-latido-de-luz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pendiente Latido de Luz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/\",\"name\":\"Yasmin\",\"description\":\"Joyer\u00eda de Plata 925 - Pendientes, pulseras, anillos, colgantes y m\u00e1s!\",\"publisher\":{\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/#organization\",\"name\":\"joyas yasmin\",\"url\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/joyasyasmin.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/IMG-20200429-WA0051.jpg\",\"contentUrl\":\"https:\\\/\\\/joyasyasmin.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/IMG-20200429-WA0051.jpg\",\"width\":1080,\"height\":545,\"caption\":\"joyas yasmin\"},\"image\":{\"@id\":\"https:\\\/\\\/joyasyasmin.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Joyas-Yasmin-217664058934169\\\/\",\"https:\\\/\\\/www.instagram.com\\\/invites\\\/contact\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pendiente Latido de Luz - Yasmin","description":"Pendiente Latido de Luz en forma de coraz\u00f3n en plata 925 con circonitas y circon central. Dise\u00f1o rom\u00e1ntico y brillante con cierre de tuerca a presi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/","og_locale":"en_US","og_title":"Pendiente Latido de Luz - Yasmin","og_description":"Pendiente Latido de Luz en forma de coraz\u00f3n en plata 925 con circonitas y circon central. Dise\u00f1o rom\u00e1ntico y brillante con cierre de tuerca a presi\u00f3n.","og_url":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/","og_site_name":"Yasmin","article_publisher":"https:\/\/www.facebook.com\/Joyas-Yasmin-217664058934169\/","article_modified_time":"2026-05-15T12:03:46+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/joyasyasmin.com\/wp-content\/uploads\/2026\/05\/pendiente-corazon-ilusion.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/","url":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/","name":"Pendiente Latido de Luz - Yasmin","isPartOf":{"@id":"https:\/\/joyasyasmin.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/#primaryimage"},"image":{"@id":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/#primaryimage"},"thumbnailUrl":"https:\/\/joyasyasmin.com\/wp-content\/uploads\/2026\/05\/pendiente-corazon-ilusion.jpg","datePublished":"2026-05-15T12:03:20+00:00","dateModified":"2026-05-15T12:03:46+00:00","description":"Pendiente Latido de Luz en forma de coraz\u00f3n en plata 925 con circonitas y circon central. Dise\u00f1o rom\u00e1ntico y brillante con cierre de tuerca a presi\u00f3n.","breadcrumb":{"@id":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/#primaryimage","url":"https:\/\/joyasyasmin.com\/wp-content\/uploads\/2026\/05\/pendiente-corazon-ilusion.jpg","contentUrl":"https:\/\/joyasyasmin.com\/wp-content\/uploads\/2026\/05\/pendiente-corazon-ilusion.jpg","width":1000,"height":1000,"caption":"venta de pendiente ilus\u00f3n en forma de coraz\u00f3n de plata 925"},{"@type":"BreadcrumbList","@id":"https:\/\/joyasyasmin.com\/en\/producto\/pendiente-latido-de-luz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/joyasyasmin.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/joyasyasmin.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Pendiente Latido de Luz"}]},{"@type":"WebSite","@id":"https:\/\/joyasyasmin.com\/en\/#website","url":"https:\/\/joyasyasmin.com\/en\/","name":"Yasmin","description":"Joyer\u00eda de Plata 925 - Pendientes, pulseras, anillos, colgantes y m\u00e1s!","publisher":{"@id":"https:\/\/joyasyasmin.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/joyasyasmin.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/joyasyasmin.com\/en\/#organization","name":"joyas yasmin","url":"https:\/\/joyasyasmin.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/joyasyasmin.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/joyasyasmin.com\/wp-content\/uploads\/2017\/06\/IMG-20200429-WA0051.jpg","contentUrl":"https:\/\/joyasyasmin.com\/wp-content\/uploads\/2017\/06\/IMG-20200429-WA0051.jpg","width":1080,"height":545,"caption":"joyas yasmin"},"image":{"@id":"https:\/\/joyasyasmin.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Joyas-Yasmin-217664058934169\/","https:\/\/www.instagram.com\/invites\/contact\/"]}]}},"_links":{"self":[{"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/product\/39257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/comments?post=39257"}],"version-history":[{"count":1,"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/product\/39257\/revisions"}],"predecessor-version":[{"id":39276,"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/product\/39257\/revisions\/39276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/media\/39258"}],"wp:attachment":[{"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/media?parent=39257"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/product_brand?post=39257"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/product_cat?post=39257"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/joyasyasmin.com\/en\/wp-json\/wp\/v2\/product_tag?post=39257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}